{"id":212,"date":"2021-10-05T16:45:19","date_gmt":"2021-10-05T16:45:19","guid":{"rendered":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/?p=212"},"modified":"2021-11-02T11:42:19","modified_gmt":"2021-11-02T11:42:19","slug":"strada-mt-electrico-24-ghz-rtr","status":"publish","type":"post","link":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/","title":{"rendered":"Strada MT el\u00e9ctrico 2,4 Ghz RTR"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/10\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR.jpg\" alt=\"\" class=\"wp-image-213\" srcset=\"https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/10\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR.jpg 300w, https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/10\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><figcaption> Strada MT Evo <\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">especificaciones:<\/h2>\n\n\n\n<p>Strada MT Evo es el cami\u00f3n definitivo para rodaduras a trav\u00e9s de todo tipo de terrenos<\/p>\n\n\n\n<p>Nuevo chasis m\u00e1s resistente de dise\u00f1o<br>Cubierta superior de aluminio<br>Nuevo esquema de colores<\/p>\n\n\n\n<p class=\"caja-destacada\"><b>Maverick<\/b> sistema de radio de 2,4 GHz.<\/p>\n\n\n\n<p>Completamente listos para ejecutar con bater\u00eda y cargador<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">caracter\u00edsticas:<\/h2>\n\n\n\n<p>MM-22 de gran alcance del motor 540<br>MSC-22 adelante \/ atr\u00e1s con control de la velocidad l\u00edmite de 13-a su vez motor de cepillado<br>MBP-22 Ni-MH de 1800mAh de la bater\u00eda incluida con Tamiya enchufe de la bater\u00eda<br>MS-22 de alta resistencia servo<br>Transmisor y receptor de 2,4 GHz con funci\u00f3n a prueba de fallos<br>De titanio de gran disipador de calor del motor anodizado<br>Chasis moldeado de tina con una distribuci\u00f3n de peso optimizado<br>Carreras de suspensi\u00f3n totalmente ajustable<br>Correa de la bater\u00eda aceptar\u00e1 ambas stick packs y las c\u00e9lulas de lado a lado<br>Resortes progresivos de aceite llenos de golpes reparables (8)<\/p>\n\n\n\n<p class=\"caja-destacada\">Tapas especiales de <b>titanio anodizado<\/b> de choque.<\/p>\n\n\n\n<p>Totalmente independiente de doble brazo de suspensi\u00f3n horquilla<br>Dif\u00edciles de cubo C-nudillos delanteros de direcci\u00f3n<br>Resistente eje de eficiencia del tren de 4wd<br>Unidad completamente ballraced tren<br>De aluminio anodizado titanio eje central de peso ligero<br>4 grandes todo terreno &#8216;bloque de remo neum\u00e1ticos<br>Atractivos m\u00faltiples rines<br>Pre-corte del cuerpo con acabado de f\u00e1brica<br>Totalmente tensores regulables en todo el<br>Paragolpes delantero y trasero moldeados<br>Doble punto de direcci\u00f3n con servo integrado de ahorro de<br>Cubierta moldeada equipo de protecci\u00f3n<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">elementos necesarios:<\/h2>\n\n\n\n<p>4 pilas AA<\/p>\n\n\n\n<p>Tienda de Hobby para toda Espa\u00f1a.<br>Envios gratis en todos nuestros productos.<br>Especializados en automodelismo<\/p>\n\n\n\n<p>www.tiendahobby.es<\/p>\n\n\n\n<h3 class=\"has-text-align-center wp-block-heading\"><span style=\"color:#7f0000\" class=\"has-inline-color\">contacto<\/span><\/h3>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<p class=\"has-text-align-center\"> Contacte con el anunciante<br><strong>desde la secci\u00f3n de comentarios<\/strong><br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"395\" height=\"349\" src=\"https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/10\/contactar-con-anunciante-e1634222078360.jpg\" alt=\"contactar con el anunciante\" class=\"wp-image-689\" srcset=\"https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/10\/contactar-con-anunciante-e1634222078360.jpg 395w, https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/10\/contactar-con-anunciante-e1634222078360-300x265.jpg 300w\" sizes=\"auto, (max-width: 395px) 100vw, 395px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>especificaciones: Strada MT Evo es el cami\u00f3n definitivo para rodaduras a trav\u00e9s de todo tipo de terrenos Nuevo chasis m\u00e1s resistente de dise\u00f1oCubierta superior de aluminioNuevo esquema de colores Maverick sistema de radio de 2,4 GHz. Completamente listos para ejecutar con bater\u00eda y cargador caracter\u00edsticas: MM-22 de gran alcance del motor 540MSC-22 adelante \/ atr\u00e1s&hellip; <a class=\"more-link\" href=\"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/\">Seguir leyendo <span class=\"screen-reader-text\">Strada MT el\u00e9ctrico 2,4 Ghz RTR<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[14,12,11],"class_list":["post-212","post","type-post","status-publish","format-standard","hentry","category-automodelismo-mejores-precios-ofertas-segunda-mano-baratos","tag-2-4-ghz","tag-rtr","tag-strada","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Strada MT el\u00e9ctrico 2,4 Ghz RTR - anuncialoquequieras<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Strada MT el\u00e9ctrico 2,4 Ghz RTR - anuncialoquequieras\" \/>\n<meta property=\"og:description\" content=\"especificaciones: Strada MT Evo es el cami\u00f3n definitivo para rodaduras a trav\u00e9s de todo tipo de terrenos Nuevo chasis m\u00e1s resistente de dise\u00f1oCubierta superior de aluminioNuevo esquema de colores Maverick sistema de radio de 2,4 GHz. Completamente listos para ejecutar con bater\u00eda y cargador caracter\u00edsticas: MM-22 de gran alcance del motor 540MSC-22 adelante \/ atr\u00e1s&hellip; Seguir leyendo Strada MT el\u00e9ctrico 2,4 Ghz RTR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/\" \/>\n<meta property=\"og:site_name\" content=\"anuncialoquequieras\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/es-la.facebook.com\/anuncialoquequieras.es\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-05T16:45:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-02T11:42:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/10\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR.jpg\" \/>\n<meta name=\"author\" content=\"Rgv\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@enClasificados\" \/>\n<meta name=\"twitter:site\" content=\"@enClasificados\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rgv\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/\"},\"author\":{\"name\":\"Rgv\",\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/#\\\/schema\\\/person\\\/f53fe5dfac42316d1265358b28dd85d3\"},\"headline\":\"Strada MT el\u00e9ctrico 2,4 Ghz RTR\",\"datePublished\":\"2021-10-05T16:45:19+00:00\",\"dateModified\":\"2021-11-02T11:42:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/\"},\"wordCount\":278,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/anuncialoquequieras.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR.jpg\",\"keywords\":[\"2.4 GHz\",\"RTR\",\"Strada\"],\"articleSection\":[\"automodelismo\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/\",\"url\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/\",\"name\":\"Strada MT el\u00e9ctrico 2,4 Ghz RTR - anuncialoquequieras\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/anuncialoquequieras.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR.jpg\",\"datePublished\":\"2021-10-05T16:45:19+00:00\",\"dateModified\":\"2021-11-02T11:42:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/#primaryimage\",\"url\":\"https:\\\/\\\/anuncialoquequieras.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR.jpg\",\"contentUrl\":\"https:\\\/\\\/anuncialoquequieras.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/strada-mt-electrico-24-ghz-rtr\\\/212\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Strada MT el\u00e9ctrico 2,4 Ghz RTR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/#website\",\"url\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/\",\"name\":\"anuncialoquequieras\",\"description\":\"nuevos y de segunda mano\",\"publisher\":{\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/#organization\",\"name\":\"anuncialoquequieras\",\"url\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/anuncialoquequieras.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/clasificados.jpg\",\"contentUrl\":\"https:\\\/\\\/anuncialoquequieras.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/clasificados.jpg\",\"width\":398,\"height\":375,\"caption\":\"anuncialoquequieras\"},\"image\":{\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/es-la.facebook.com\\\/anuncialoquequieras.es\\\/\",\"https:\\\/\\\/x.com\\\/enClasificados\",\"https:\\\/\\\/www.instagram.com\\\/anuncialoquequieras\\\/\",\"https:\\\/\\\/www.youtube.com\\\/watch?v=KxiauMKONpM\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/#\\\/schema\\\/person\\\/f53fe5dfac42316d1265358b28dd85d3\",\"name\":\"Rgv\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2ab5a5d22203883bce4ccbb918fd9471093e872b801a6e18a4b43703a3e9488?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2ab5a5d22203883bce4ccbb918fd9471093e872b801a6e18a4b43703a3e9488?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d2ab5a5d22203883bce4ccbb918fd9471093e872b801a6e18a4b43703a3e9488?s=96&d=mm&r=g\",\"caption\":\"Rgv\"},\"sameAs\":[\"https:\\\/\\\/anuncialoquequieras.com\"],\"url\":\"https:\\\/\\\/anuncialoquequieras.com\\\/clasificados-ofertas-segunda-mano\\\/author\\\/rgv-anuncialoquequieras\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Strada MT el\u00e9ctrico 2,4 Ghz RTR - anuncialoquequieras","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/","og_locale":"es_ES","og_type":"article","og_title":"Strada MT el\u00e9ctrico 2,4 Ghz RTR - anuncialoquequieras","og_description":"especificaciones: Strada MT Evo es el cami\u00f3n definitivo para rodaduras a trav\u00e9s de todo tipo de terrenos Nuevo chasis m\u00e1s resistente de dise\u00f1oCubierta superior de aluminioNuevo esquema de colores Maverick sistema de radio de 2,4 GHz. Completamente listos para ejecutar con bater\u00eda y cargador caracter\u00edsticas: MM-22 de gran alcance del motor 540MSC-22 adelante \/ atr\u00e1s&hellip; Seguir leyendo Strada MT el\u00e9ctrico 2,4 Ghz RTR","og_url":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/","og_site_name":"anuncialoquequieras","article_publisher":"https:\/\/es-la.facebook.com\/anuncialoquequieras.es\/","article_published_time":"2021-10-05T16:45:19+00:00","article_modified_time":"2021-11-02T11:42:19+00:00","og_image":[{"url":"https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/10\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR.jpg","type":"","width":"","height":""}],"author":"Rgv","twitter_card":"summary_large_image","twitter_creator":"@enClasificados","twitter_site":"@enClasificados","twitter_misc":{"Escrito por":"Rgv","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/#article","isPartOf":{"@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/"},"author":{"name":"Rgv","@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/#\/schema\/person\/f53fe5dfac42316d1265358b28dd85d3"},"headline":"Strada MT el\u00e9ctrico 2,4 Ghz RTR","datePublished":"2021-10-05T16:45:19+00:00","dateModified":"2021-11-02T11:42:19+00:00","mainEntityOfPage":{"@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/"},"wordCount":278,"commentCount":0,"publisher":{"@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/#organization"},"image":{"@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/#primaryimage"},"thumbnailUrl":"https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/10\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR.jpg","keywords":["2.4 GHz","RTR","Strada"],"articleSection":["automodelismo"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/","url":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/","name":"Strada MT el\u00e9ctrico 2,4 Ghz RTR - anuncialoquequieras","isPartOf":{"@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/#website"},"primaryImageOfPage":{"@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/#primaryimage"},"image":{"@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/#primaryimage"},"thumbnailUrl":"https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/10\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR.jpg","datePublished":"2021-10-05T16:45:19+00:00","dateModified":"2021-11-02T11:42:19+00:00","breadcrumb":{"@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/#primaryimage","url":"https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/10\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR.jpg","contentUrl":"https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/10\/clasificados_spain_RC-STRADA-MT-ELECTRICO-24-GHZ-RTR.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/strada-mt-electrico-24-ghz-rtr\/212\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/"},{"@type":"ListItem","position":2,"name":"Strada MT el\u00e9ctrico 2,4 Ghz RTR"}]},{"@type":"WebSite","@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/#website","url":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/","name":"anuncialoquequieras","description":"nuevos y de segunda mano","publisher":{"@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/#organization","name":"anuncialoquequieras","url":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/#\/schema\/logo\/image\/","url":"https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/12\/clasificados.jpg","contentUrl":"https:\/\/anuncialoquequieras.com\/wp-content\/uploads\/2021\/12\/clasificados.jpg","width":398,"height":375,"caption":"anuncialoquequieras"},"image":{"@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/es-la.facebook.com\/anuncialoquequieras.es\/","https:\/\/x.com\/enClasificados","https:\/\/www.instagram.com\/anuncialoquequieras\/","https:\/\/www.youtube.com\/watch?v=KxiauMKONpM"]},{"@type":"Person","@id":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/#\/schema\/person\/f53fe5dfac42316d1265358b28dd85d3","name":"Rgv","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d2ab5a5d22203883bce4ccbb918fd9471093e872b801a6e18a4b43703a3e9488?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d2ab5a5d22203883bce4ccbb918fd9471093e872b801a6e18a4b43703a3e9488?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d2ab5a5d22203883bce4ccbb918fd9471093e872b801a6e18a4b43703a3e9488?s=96&d=mm&r=g","caption":"Rgv"},"sameAs":["https:\/\/anuncialoquequieras.com"],"url":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/author\/rgv-anuncialoquequieras\/"}]}},"_links":{"self":[{"href":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/wp-json\/wp\/v2\/posts\/212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/wp-json\/wp\/v2\/comments?post=212"}],"version-history":[{"count":7,"href":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/wp-json\/wp\/v2\/posts\/212\/revisions"}],"predecessor-version":[{"id":1200,"href":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/wp-json\/wp\/v2\/posts\/212\/revisions\/1200"}],"wp:attachment":[{"href":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/wp-json\/wp\/v2\/media?parent=212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/wp-json\/wp\/v2\/categories?post=212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/anuncialoquequieras.com\/clasificados-ofertas-segunda-mano\/wp-json\/wp\/v2\/tags?post=212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}